{"id":93478,"date":"2021-02-25T16:49:34","date_gmt":"2021-02-25T15:49:34","guid":{"rendered":"https:\/\/xanatis.com\/~barcelonasotheby\/?page_id=93478"},"modified":"2024-03-03T18:04:54","modified_gmt":"2024-03-03T17:04:54","slug":"roses","status":"publish","type":"page","link":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/","title":{"rendered":"Cases de Luxe en Roses Girona"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">En Costa Brava Sotheby&#8217;s\u00a0<\/span><span style=\"font-weight: 400;\">International<\/span><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\">Realty<\/span><span style=\"font-weight: 400;\">\u00a0estem especialitzats en la compra i venda d&#8217;immobles residencials i en la promoci\u00f3 de projectes d&#8217;obra nova, tots situats en les millors zones del litoral giron\u00ed i triats amb la finalitat de satisfer als clients m\u00e9s exigents.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Situat en el\u00a0<\/span><span style=\"font-weight: 400;\">norte<\/span><span style=\"font-weight: 400;\">\u00a0del Golf de Roses, a la comarca de l&#8217;Alt Empord\u00e0, Roses \u00e9s un gran centre tur\u00edstic: disposa de dos ports, un pesquer i un altre esportiu, i nombrosos restaurants i urbanitzacions. Compta amb una llarga platja de sorra i incomptables cales, entre les quals destaquen l\u2019<\/span><span style=\"font-weight: 400;\">Almadrava<\/span><span style=\"font-weight: 400;\">, Canyelles\u00a0<\/span><span style=\"font-weight: 400;\">Petites<\/span><span style=\"font-weight: 400;\">, Punta\u00a0<\/span><span style=\"font-weight: 400;\">Flaconera<\/span><span style=\"font-weight: 400;\">\u00a0i\u00a0<\/span><span style=\"font-weight: 400;\">Montjoi<\/span><span style=\"font-weight: 400;\">. A m\u00e9s, per als amants de la cultura, a Roses s&#8217;hagin restes arqueol\u00f2giques del paleol\u00edtic: d\u00f2lmens i menhirs amb m\u00e9s de tres mil anys d&#8217;hist\u00f2ria.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el nostre cat\u00e0leg trobar\u00e0 exclusives cases en venda a Roses, Costa Brava, totes elles seleccionades complint nostres m\u00e9s exigents est\u00e0ndards de qualitat, sempre pensant en el benestar i l&#8217;inter\u00e8s dels futurs propietaris o inversors.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Costa Brava Sotheby&#8217;s\u00a0International\u00a0Realty\u00a0estem especialitzats en la compra i venda d&#8217;immobles residencials i en la promoci\u00f3 de projectes d&#8217;obra nova,<a class=\"more-link\" href=\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/\">Llegir M\u00e9s<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":93347,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-listado.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cases de Luxe en Roses Girona - Barcelona Sotheby&#039;s\" \/>\n<meta property=\"og:description\" content=\"En Costa Brava Sotheby&#8217;s\u00a0International\u00a0Realty\u00a0estem especialitzats en la compra i venda d&#8217;immobles residencials i en la promoci\u00f3 de projectes d&#8217;obra nova,Llegir M\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/\" \/>\n<meta property=\"og:site_name\" content=\"Barcelona Sotheby&#039;s Realty\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-03T17:04:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/#organization\",\"name\":\"Barcelona Sotheby's Realty\",\"url\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/#logo\",\"inLanguage\":\"ca\",\"url\":\"https:\/\/www.barcelona-sothebysrealty.com\/wp-content\/uploads\/2023\/10\/sothebys-barcelona-logo-3.png\",\"contentUrl\":\"https:\/\/www.barcelona-sothebysrealty.com\/wp-content\/uploads\/2023\/10\/sothebys-barcelona-logo-3.png\",\"width\":274,\"height\":274,\"caption\":\"Barcelona Sotheby's Realty\"},\"image\":{\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/#website\",\"url\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/\",\"name\":\"Barcelona Sotheby&#039;s\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/#webpage\",\"url\":\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/\",\"name\":\"Cases de Luxe en Roses Girona - Barcelona Sotheby&#039;s\",\"isPartOf\":{\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/#website\"},\"datePublished\":\"2021-02-25T15:49:34+00:00\",\"dateModified\":\"2024-03-03T17:04:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Barcelona i Costa Brava &#8211; Compra i venda de cases de luxe\",\"item\":\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cases de Luxe en Costa Brava\",\"item\":\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/costa-brava\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cases de Luxe en Roses Girona\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ca_ES","og_type":"article","og_title":"Cases de Luxe en Roses Girona - Barcelona Sotheby&#039;s","og_description":"En Costa Brava Sotheby&#8217;s\u00a0International\u00a0Realty\u00a0estem especialitzats en la compra i venda d&#8217;immobles residencials i en la promoci\u00f3 de projectes d&#8217;obra nova,Llegir M\u00e9s","og_url":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/","og_site_name":"Barcelona Sotheby's Realty","article_modified_time":"2024-03-03T17:04:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.barcelona-sothebysrealty.com\/es\/#organization","name":"Barcelona Sotheby's Realty","url":"https:\/\/www.barcelona-sothebysrealty.com\/es\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.barcelona-sothebysrealty.com\/es\/#logo","inLanguage":"ca","url":"https:\/\/www.barcelona-sothebysrealty.com\/wp-content\/uploads\/2023\/10\/sothebys-barcelona-logo-3.png","contentUrl":"https:\/\/www.barcelona-sothebysrealty.com\/wp-content\/uploads\/2023\/10\/sothebys-barcelona-logo-3.png","width":274,"height":274,"caption":"Barcelona Sotheby's Realty"},"image":{"@id":"https:\/\/www.barcelona-sothebysrealty.com\/es\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.barcelona-sothebysrealty.com\/es\/#website","url":"https:\/\/www.barcelona-sothebysrealty.com\/es\/","name":"Barcelona Sotheby&#039;s","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.barcelona-sothebysrealty.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barcelona-sothebysrealty.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/#webpage","url":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/","name":"Cases de Luxe en Roses Girona - Barcelona Sotheby&#039;s","isPartOf":{"@id":"https:\/\/www.barcelona-sothebysrealty.com\/es\/#website"},"datePublished":"2021-02-25T15:49:34+00:00","dateModified":"2024-03-03T17:04:54+00:00","breadcrumb":{"@id":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/roses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Barcelona i Costa Brava &#8211; Compra i venda de cases de luxe","item":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/"},{"@type":"ListItem","position":3,"name":"Cases de Luxe en Costa Brava","item":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/cases-venda\/costa-brava\/"},{"@type":"ListItem","position":4,"name":"Cases de Luxe en Roses Girona"}]}]}},"_links":{"self":[{"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/pages\/93478"}],"collection":[{"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/comments?post=93478"}],"version-history":[{"count":0,"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/pages\/93478\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/pages\/93347"}],"wp:attachment":[{"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/media?parent=93478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}