{"id":93508,"date":"2021-03-09T10:43:40","date_gmt":"2021-03-09T09:43:40","guid":{"rendered":"https:\/\/xanatis.com\/~barcelonasotheby\/?page_id=93508"},"modified":"2024-04-17T16:39:33","modified_gmt":"2024-04-17T14:39:33","slug":"immobiliaria-begur","status":"publish","type":"page","link":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/","title":{"rendered":"Habitatges en venda a Begur"},"content":{"rendered":"<p>Begur \u00e9s una joia de la Costa Brava. Presenta un ampli patrimoni historicocultural, des de restes de la fortalesa situada a la part m\u00e9s alta de la ciutat que data del segle XI fins a les \u00faltimes cases indianes constru\u00efdes al segle XIX. Tamb\u00e9, Begur posseeix un litoral ple de cales i platges de sorra fina o petits cants: Aiguablava, Fornells, Fonda, Sa Tuna, Aiguafreda, Sa Riera i Illa Roja. Totes elles envoltades de penya-segats i boscos que brinden un encant sense igual.<\/p>\n<p>Oferim als nostres compradors nacionals i internacionals una selecci\u00f3 \u00fanica de propietats de luxe, cases modernes, viles exclusives i apartaments extraordinaris en venda en aquesta bella ciutat de la part central de la Costa Brava.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Begur \u00e9s una joia de la Costa Brava. Presenta un ampli patrimoni historicocultural, des de restes de la fortalesa situada<a class=\"more-link\" href=\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/\">Llegir M\u00e9s<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-listado.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Habitatges en venda a Begur - Barcelona Sotheby&#039;s\" \/>\n<meta property=\"og:description\" content=\"Begur \u00e9s una joia de la Costa Brava. Presenta un ampli patrimoni historicocultural, des de restes de la fortalesa situadaLlegir M\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/\" \/>\n<meta property=\"og:site_name\" content=\"Barcelona Sotheby&#039;s Realty\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-17T14:39:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/#organization\",\"name\":\"Barcelona Sotheby's Realty\",\"url\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/#logo\",\"inLanguage\":\"ca\",\"url\":\"https:\/\/www.barcelona-sothebysrealty.com\/wp-content\/uploads\/2023\/10\/sothebys-barcelona-logo-3.png\",\"contentUrl\":\"https:\/\/www.barcelona-sothebysrealty.com\/wp-content\/uploads\/2023\/10\/sothebys-barcelona-logo-3.png\",\"width\":274,\"height\":274,\"caption\":\"Barcelona Sotheby's Realty\"},\"image\":{\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/#website\",\"url\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/\",\"name\":\"Barcelona Sotheby&#039;s\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/#webpage\",\"url\":\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/\",\"name\":\"Habitatges en venda a Begur - Barcelona Sotheby&#039;s\",\"isPartOf\":{\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/es\/#website\"},\"datePublished\":\"2021-03-09T09:43:40+00:00\",\"dateModified\":\"2024-04-17T14:39:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.barcelona-sothebysrealty.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Habitatges en venda a Begur\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ca_ES","og_type":"article","og_title":"Habitatges en venda a Begur - Barcelona Sotheby&#039;s","og_description":"Begur \u00e9s una joia de la Costa Brava. Presenta un ampli patrimoni historicocultural, des de restes de la fortalesa situadaLlegir M\u00e9s","og_url":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/","og_site_name":"Barcelona Sotheby's Realty","article_modified_time":"2024-04-17T14:39:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.barcelona-sothebysrealty.com\/es\/#organization","name":"Barcelona Sotheby's Realty","url":"https:\/\/www.barcelona-sothebysrealty.com\/es\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.barcelona-sothebysrealty.com\/es\/#logo","inLanguage":"ca","url":"https:\/\/www.barcelona-sothebysrealty.com\/wp-content\/uploads\/2023\/10\/sothebys-barcelona-logo-3.png","contentUrl":"https:\/\/www.barcelona-sothebysrealty.com\/wp-content\/uploads\/2023\/10\/sothebys-barcelona-logo-3.png","width":274,"height":274,"caption":"Barcelona Sotheby's Realty"},"image":{"@id":"https:\/\/www.barcelona-sothebysrealty.com\/es\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.barcelona-sothebysrealty.com\/es\/#website","url":"https:\/\/www.barcelona-sothebysrealty.com\/es\/","name":"Barcelona Sotheby&#039;s","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/www.barcelona-sothebysrealty.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barcelona-sothebysrealty.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/#webpage","url":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/","name":"Habitatges en venda a Begur - Barcelona Sotheby&#039;s","isPartOf":{"@id":"https:\/\/www.barcelona-sothebysrealty.com\/es\/#website"},"datePublished":"2021-03-09T09:43:40+00:00","dateModified":"2024-04-17T14:39:33+00:00","breadcrumb":{"@id":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/immobiliaria-begur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Habitatges en venda a Begur"}]}]}},"_links":{"self":[{"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/pages\/93508"}],"collection":[{"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/comments?post=93508"}],"version-history":[{"count":0,"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/pages\/93508\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.barcelona-sothebysrealty.com\/ca\/wp-json\/wp\/v2\/media?parent=93508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}